{"id":1046,"date":"2016-11-06T00:25:56","date_gmt":"2016-11-05T23:25:56","guid":{"rendered":"http:\/\/kawallaby.com\/?p=1046"},"modified":"2016-12-20T23:17:33","modified_gmt":"2016-12-20T22:17:33","slug":"decouverte-du-musee-archeologique-asnapio-a-villeneuve-d-ascq","status":"publish","type":"post","link":"https:\/\/kawallaby.com\/index.php\/2016\/11\/06\/decouverte-du-musee-archeologique-asnapio-a-villeneuve-d-ascq\/","title":{"rendered":"D\u00e9couverte du mus\u00e9e arch\u00e9ologique Asnapio \u00e0 Villeneuve d Ascq"},"content":{"rendered":"<p>[et_pb_section admin_label=\u00a0\u00bbsection\u00a0\u00bb][et_pb_row admin_label=\u00a0\u00bbrow\u00a0\u00bb][et_pb_column type=\u00a0\u00bb2_3&Prime;][et_pb_text admin_label=\u00a0\u00bbTexte\u00a0\u00bb background_layout=\u00a0\u00bblight\u00a0\u00bb text_orientation=\u00a0\u00bbleft\u00a0\u00bb use_border_color=\u00a0\u00bboff\u00a0\u00bb border_color=\u00a0\u00bb#ffffff\u00a0\u00bb border_style=\u00a0\u00bbsolid\u00a0\u00bb]<\/p>\n<p>Ateliers et\u00a0d\u00e9guisements, animations et surprises, balade et d\u00e9gustations&#8230; Retrouve cette semaine une vid\u00e9o<strong> d\u00e9couverte sur le mus\u00e9e arch\u00e9ologique Asnapio<\/strong> de Villeneuve d&rsquo;Ascq, le jour m\u00eame d&rsquo;Halloween, en cliquant sur l&rsquo;image ci-contre.<\/p>\n<p>Plus d&rsquo;infos sur le site officiel\u00a0 en cliquant <a href=\"http:\/\/www.villeneuvedascq.fr\/asnapio.html\"><strong>ici<\/strong> <\/a>et sur la page Facebook du mus\u00e9e en cliquant\u00a0<a href=\"https:\/\/www.facebook.com\/pages\/Parc-arch%C3%A9ologique-Asnapio\/790808560932479?fref=ts\"><strong>ici<\/strong><\/a>.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_3&Prime;][et_pb_image admin_label=\u00a0\u00bbImage\u00a0\u00bb src=\u00a0\u00bbhttp:\/\/kawallaby.com\/wp-content\/uploads\/2016\/11\/161015-image-vid\u00e9os-003-LOW.png\u00a0\u00bb show_in_lightbox=\u00a0\u00bboff\u00a0\u00bb url_new_window=\u00a0\u00bbon\u00a0\u00bb use_overlay=\u00a0\u00bboff\u00a0\u00bb animation=\u00a0\u00bboff\u00a0\u00bb sticky=\u00a0\u00bboff\u00a0\u00bb align=\u00a0\u00bbleft\u00a0\u00bb force_fullwidth=\u00a0\u00bboff\u00a0\u00bb always_center_on_mobile=\u00a0\u00bbon\u00a0\u00bb use_border_color=\u00a0\u00bboff\u00a0\u00bb border_color=\u00a0\u00bb#ffffff\u00a0\u00bb border_style=\u00a0\u00bbsolid\u00a0\u00bb url=\u00a0\u00bbhttps:\/\/www.youtube.com\/watch?v=n2JT1UJctm8&Prime;] [\/et_pb_image][\/et_pb_column][\/et_pb_row][et_pb_row admin_label=\u00a0\u00bbrow\u00a0\u00bb][et_pb_column type=\u00a0\u00bb2_3&Prime;][et_pb_text admin_label=\u00a0\u00bbTexte\u00a0\u00bb background_layout=\u00a0\u00bblight\u00a0\u00bb text_orientation=\u00a0\u00bbleft\u00a0\u00bb use_border_color=\u00a0\u00bboff\u00a0\u00bb border_color=\u00a0\u00bb#ffffff\u00a0\u00bb border_style=\u00a0\u00bbsolid\u00a0\u00bb text_font_size=\u00a0\u00bb10&Prime; text_text_color=\u00a0\u00bb#5b5b5b\u00a0\u00bb]<\/p>\n<p>Auteur de l&rsquo;image : kawallaby.com<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_3&Prime;][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ateliers et\u00a0d\u00e9guisements, animations et surprises, balade et d\u00e9gustations&#8230; Retrouve cette semaine une vid\u00e9o d\u00e9couverte sur le mus\u00e9e arch\u00e9ologique Asnapio de Villeneuve d&rsquo;Ascq, le jour m\u00eame d&rsquo;Halloween, en cliquant sur l&rsquo;image ci-contre. Plus d&rsquo;infos sur le site officiel\u00a0 en cliquant ici et sur la page Facebook du mus\u00e9e en cliquant\u00a0ici. Auteur de l&rsquo;image : kawallaby.com<\/p>\n","protected":false},"author":1,"featured_media":1052,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[34,11],"tags":[],"_links":{"self":[{"href":"https:\/\/kawallaby.com\/index.php\/wp-json\/wp\/v2\/posts\/1046"}],"collection":[{"href":"https:\/\/kawallaby.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/kawallaby.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/kawallaby.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/kawallaby.com\/index.php\/wp-json\/wp\/v2\/comments?post=1046"}],"version-history":[{"count":5,"href":"https:\/\/kawallaby.com\/index.php\/wp-json\/wp\/v2\/posts\/1046\/revisions"}],"predecessor-version":[{"id":1121,"href":"https:\/\/kawallaby.com\/index.php\/wp-json\/wp\/v2\/posts\/1046\/revisions\/1121"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/kawallaby.com\/index.php\/wp-json\/wp\/v2\/media\/1052"}],"wp:attachment":[{"href":"https:\/\/kawallaby.com\/index.php\/wp-json\/wp\/v2\/media?parent=1046"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/kawallaby.com\/index.php\/wp-json\/wp\/v2\/categories?post=1046"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/kawallaby.com\/index.php\/wp-json\/wp\/v2\/tags?post=1046"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}