{"id":979,"date":"2016-10-23T14:30:48","date_gmt":"2016-10-23T13:30:48","guid":{"rendered":"http:\/\/kawallaby.com\/?p=979"},"modified":"2016-10-23T15:00:13","modified_gmt":"2016-10-23T14:00:13","slug":"the-coffee-time-machine-sur-le-son-dans-star-wars","status":"publish","type":"post","link":"https:\/\/kawallaby.com\/index.php\/2016\/10\/23\/the-coffee-time-machine-sur-le-son-dans-star-wars\/","title":{"rendered":"The Coffee Time Machine sur le son dans Star Wars"},"content":{"rendered":"<p>[et_pb_section admin_label=\u00a0\u00bbsection\u00a0\u00bb][et_pb_row admin_label=\u00a0\u00bbrow\u00a0\u00bb][et_pb_column type=\u00a0\u00bb2_3&Prime;][et_pb_text admin_label=\u00a0\u00bbTexte\u00a0\u00bb background_layout=\u00a0\u00bblight\u00a0\u00bb text_orientation=\u00a0\u00bbleft\u00a0\u00bb use_border_color=\u00a0\u00bboff\u00a0\u00bb border_color=\u00a0\u00bb#ffffff\u00a0\u00bb border_style=\u00a0\u00bbsolid\u00a0\u00bb]<\/p>\n<p>Aujourd&rsquo;hui, nouvelle chronique sur la cha\u00eene YouTube du Wallaby, j&rsquo;ai nomm\u00e9 :<strong> The Coffee Time Machine<\/strong>, LA machine qui va vous faire red\u00e9couvrir tout un pan de la culture pop \u00e0 travers le filtre d&rsquo;une excentrique approche\u00a0scientifico-d\u00e9raisonnable.<\/p>\n<p>Pour ce premier \u00e9pisode, la machine \u00e0 remonter le temps caf\u00e9in\u00e9 (oui cela ne veut rien dire, vous ne r\u00eavez absolument pas) s&rsquo;attaque au cas vu et revu du<strong> son dans l&rsquo;espace (clique sur l&rsquo;image pour acc\u00e9der \u00e0 la vid\u00e9o)<\/strong>, et en particulier dans Star Wars, mais bien entendu vu sous l&rsquo;angle consternant d&rsquo;une mati\u00e8re grise au fort relent de caf\u00e9\u00a0bien trop\u00a0torr\u00e9fi\u00e9.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_3&Prime;][et_pb_image admin_label=\u00a0\u00bbImage\u00a0\u00bb src=\u00a0\u00bbhttp:\/\/kawallaby.com\/wp-content\/uploads\/2016\/10\/TITIRE-Ep1-SON-VS-SW.png\u00a0\u00bb show_in_lightbox=\u00a0\u00bboff\u00a0\u00bb url=\u00a0\u00bbhttps:\/\/www.youtube.com\/watch?v=9ZzJZeGtt5M\u00a0\u00bb url_new_window=\u00a0\u00bbon\u00a0\u00bb use_overlay=\u00a0\u00bboff\u00a0\u00bb animation=\u00a0\u00bboff\u00a0\u00bb sticky=\u00a0\u00bboff\u00a0\u00bb align=\u00a0\u00bbleft\u00a0\u00bb force_fullwidth=\u00a0\u00bboff\u00a0\u00bb always_center_on_mobile=\u00a0\u00bbon\u00a0\u00bb use_border_color=\u00a0\u00bboff\u00a0\u00bb border_color=\u00a0\u00bb#ffffff\u00a0\u00bb border_style=\u00a0\u00bbsolid\u00a0\u00bb] [\/et_pb_image][\/et_pb_column][\/et_pb_row][et_pb_row admin_label=\u00a0\u00bbrow\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime;][et_pb_text admin_label=\u00a0\u00bbTexte\u00a0\u00bb background_layout=\u00a0\u00bblight\u00a0\u00bb text_orientation=\u00a0\u00bbleft\u00a0\u00bb use_border_color=\u00a0\u00bboff\u00a0\u00bb border_color=\u00a0\u00bb#ffffff\u00a0\u00bb border_style=\u00a0\u00bbsolid\u00a0\u00bb]<\/p>\n<p>Pour ceux qui seraient encore l\u00e0, \u00e0 perdre cinq minutes de leur vie en lisant ce texte pseudo-humoristique, sachez que la suite contient des <strong>SPOILERS<\/strong> si vous n&rsquo;avez pas encore regard\u00e9 la vid\u00e9o (honte \u00e0 vous), vous \u00eates pr\u00e9venu.<\/p>\n<p><em>Le son EST (j&rsquo;ai bien dit EST) une <strong>vibration<\/strong> des mol\u00e9cules dans l&rsquo;air, ou de tout type de\u00a0particules dans la mati\u00e8re. Ainsi pour produire un son, nos cordes vocales vibrent et font donc vibrer l&rsquo;air pour produire le dit son, tandis que nos oreilles contiennent tout un m\u00e9canisme \u00e0 m\u00eame de vibrer\u00a0lorsque l&rsquo;air vibre. Ainsi si tel est le cas, un message nerveux sera envoy\u00e9 et interpr\u00e9t\u00e9 par notre cerveau.<\/em><\/p>\n<p><em>Si la vibration des particules est irr\u00e9guli\u00e8re, on obtient un <strong>bruit<\/strong>, alors que si elle est structur\u00e9e et harmonieuse, on obtient un <strong>son<\/strong>. C&rsquo;est enfin l&rsquo;amplitude et la fr\u00e9quence de ce son qui d\u00e9finissent l&rsquo;intensit\u00e9 et la hauteur du son.<\/em><\/p>\n<p><em>Cependant vous l&rsquo;aurez compris, s&rsquo;il n&rsquo;y a rien pour vibrer, alors il ne peut y avoir de son&#8230; Donc pas de son dans l&rsquo;espace puisqu&rsquo;il est <strong>vide<\/strong> de toute particule (pour \u00eatre plus rigoureux, il y en a beaucoup trop peu).<\/em><\/p>\n<p>Donc <strong>voila pour les petites explications succinctes<\/strong> li\u00e9es \u00e0 la vid\u00e9o, dont le format est un peu bref. N&rsquo;h\u00e9sitez pas \u00e0 chercher plus d&rsquo;infos sur le net. Bye<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row admin_label=\u00a0\u00bbrow\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime;][et_pb_text admin_label=\u00a0\u00bbTexte\u00a0\u00bb background_layout=\u00a0\u00bblight\u00a0\u00bb text_orientation=\u00a0\u00bbleft\u00a0\u00bb use_border_color=\u00a0\u00bboff\u00a0\u00bb border_color=\u00a0\u00bb#ffffff\u00a0\u00bb border_style=\u00a0\u00bbsolid\u00a0\u00bb text_font_size=\u00a0\u00bb10&Prime; text_text_color=\u00a0\u00bb#6b6b6b\u00a0\u00bb]<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Auteur de l&rsquo;image d&rsquo;ent\u00eate : Sam Howzit<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Aujourd&rsquo;hui, nouvelle chronique sur la cha\u00eene YouTube du Wallaby, j&rsquo;ai nomm\u00e9 : The Coffee Time Machine, LA machine qui va vous faire red\u00e9couvrir tout un pan de la culture pop \u00e0 travers le filtre d&rsquo;une excentrique approche\u00a0scientifico-d\u00e9raisonnable. Pour ce premier \u00e9pisode, la machine \u00e0 remonter le temps caf\u00e9in\u00e9 (oui cela ne veut rien dire, vous [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":982,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[34,11],"tags":[],"_links":{"self":[{"href":"https:\/\/kawallaby.com\/index.php\/wp-json\/wp\/v2\/posts\/979"}],"collection":[{"href":"https:\/\/kawallaby.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/kawallaby.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/kawallaby.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/kawallaby.com\/index.php\/wp-json\/wp\/v2\/comments?post=979"}],"version-history":[{"count":7,"href":"https:\/\/kawallaby.com\/index.php\/wp-json\/wp\/v2\/posts\/979\/revisions"}],"predecessor-version":[{"id":988,"href":"https:\/\/kawallaby.com\/index.php\/wp-json\/wp\/v2\/posts\/979\/revisions\/988"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/kawallaby.com\/index.php\/wp-json\/wp\/v2\/media\/982"}],"wp:attachment":[{"href":"https:\/\/kawallaby.com\/index.php\/wp-json\/wp\/v2\/media?parent=979"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/kawallaby.com\/index.php\/wp-json\/wp\/v2\/categories?post=979"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/kawallaby.com\/index.php\/wp-json\/wp\/v2\/tags?post=979"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}